{"id":4443,"date":"2026-02-24T15:02:45","date_gmt":"2026-02-24T14:02:45","guid":{"rendered":"https:\/\/prezode-initiative.org\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/"},"modified":"2026-03-25T17:48:22","modified_gmt":"2026-03-25T16:48:22","slug":"como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud","status":"publish","type":"post","link":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/","title":{"rendered":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?"},"content":{"rendered":"\n<p><\/p>\n\n<h2 class=\"wp-block-heading\">El 5 de marzo de 2026, PREZODE convocar\u00e1 una mesa redonda para examinar c\u00f3mo definir y medir indicadores que capten el valor a\u00f1adido y el impacto de la prevenci\u00f3n de las enfermedades zoon\u00f3ticas.<\/h2>\n\n<p><\/p>\n\n<p>Prevenir la aparici\u00f3n de enfermedades zoon\u00f3ticas es uno de los retos definitorios de nuestro tiempo, y uno que es intr\u00ednsecamente intersectorial. En un mundo \u00abUna sola salud\u00bb, la prevenci\u00f3n requiere una acci\u00f3n coordinada entre la salud humana, la sanidad animal y los ecosistemas, y exige herramientas y marcos que puedan demostrar su valor mucho antes de que se desencadene una crisis. <\/p>\n\n<p>El debate abordar\u00e1 los retos metodol\u00f3gicos, las lagunas de datos y las consideraciones de equidad que conforman -y a menudo limitan- la forma en que controlamos, evaluamos y justificamos la inversi\u00f3n en prevenci\u00f3n.<\/p>\n\n<p><\/p>\n\n<p>Esta sesi\u00f3n tiene lugar el<sup>5 de<\/sup> marzo - 16:00 y 17:30 CET - (15:00-16:30 UTC)<\/p>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-pz-orange-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/inrae-fr.zoom.us\/webinar\/register\/WN_LRbkaicwSAm69P79VqD_Sg\" target=\"_blank\" rel=\"noreferrer noopener\">Haz clic aqu\u00ed para inscribirte en la sesi\u00f3n<\/a><\/div>\n<\/div>\n\n<p><\/p>\n\n<p>En la mesa redonda participar\u00e1n <strong>el Dr. Osman Ahmed Dar<\/strong>, Asesor Principal de los Centros Africanos para el Control y la Prevenci\u00f3n de Enfermedades (CDC de \u00c1frica) y miembro del Grupo de Expertos de Alto Nivel sobre Una Sola Salud (OHHLEP); <strong>la Prof. Wanda Markotter<\/strong>, Directora del Centro de Zoonosis Virales de la Universidad de Pretoria y Copresidenta del OHHLEP; <strong>el Dr. Marc Leandri<\/strong>, Profesor Asociado de Econom\u00eda de la Universidad de Par\u00eds Saclay e investigador de UMI SOURCE-IRD, y <strong>Yoeri Booijink, <\/strong>Economista de Una Sola Salud del CIRAD. Moderar\u00e1 el debate <strong>la Dra. Christina Pettan-Brewer<\/strong>, l\u00edder mundial de Una Salud en la Facultad de Medicina de la Universidad de Washington. <em>(Ver biograf\u00edas m\u00e1s abajo)<\/em> <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4193\" src=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-1024x1024.jpg\" alt=\"\" class=\"wp-image-4193\" srcset=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-1024x1024.jpg 1024w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-300x300.jpg 300w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-150x150.jpg 150w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-768x768.jpg 768w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955-254x254.jpg 254w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/Markotter-photo-scaled-e1772199133955.jpg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Wanda Markotter, Directora Interina de \u00c1frica Futura, Universidad de Pretoria<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"742\" height=\"716\" data-id=\"4202\" src=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/oD-pic-5.jpg\" alt=\"\" class=\"wp-image-4202\" srcset=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/oD-pic-5.jpg 742w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/oD-pic-5-300x289.jpg 300w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/><figcaption class=\"wp-element-caption\">Osman Ahmed Dar, Asesor Principal de Pol\u00edtica y Estrategia, Africa CDC<\/figcaption><\/figure>\n<\/figure>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"4196\" src=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/ACA_3381-copie-768x1024.jpg\" alt=\"\" class=\"wp-image-4196\"\/><figcaption class=\"wp-element-caption\">Christina Pettan-Brewer, Profesora Asociada, Universidad de Washington<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"965\" data-id=\"4198\" src=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/marc_leandri_1MB-1024x965.jpeg\" alt=\"\" class=\"wp-image-4198\"\/><figcaption class=\"wp-element-caption\">Marc Leandri,<br\/>Profesor asociado de econom\u00eda,UVSQ<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" data-id=\"4200\" src=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/YB.jpg\" alt=\"\" class=\"wp-image-4200\" srcset=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/YB.jpg 640w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/YB-300x300.jpg 300w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/YB-150x150.jpg 150w, https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/YB-254x254.jpg 254w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Yoeri Booijink,<br\/> Una economista de la salud, CIRAD<\/figcaption><\/figure>\n<\/figure>\n\n<p><\/p>\n\n<h3 class=\"wp-block-heading\">La paradoja de la prevenci\u00f3n<\/h3>\n\n<p><\/p>\n\n<p>La medici\u00f3n del impacto de la prevenci\u00f3n de las enfermedades zoon\u00f3ticas se enfrenta a una paradoja fundamental: cuando la prevenci\u00f3n tiene \u00e9xito, no ocurre nada: ni brotes, ni propagaci\u00f3n, ni transmisi\u00f3n. Esta invisibilidad hace extremadamente dif\u00edcil demostrar el valor a\u00f1adido de la prevenci\u00f3n, justificar la inversi\u00f3n o mantener el compromiso pol\u00edtico. Para superarlo, es necesario desarrollar indicadores capaces de captar los resultados \u00abnegativos\u00bb (evitar la propagaci\u00f3n, reducir el riesgo de transmisi\u00f3n, mejorar la resistencia del sistema) e identificar qu\u00e9 m\u00e9tricas de proceso, producto, resultado, aproximaci\u00f3n y alerta temprana son m\u00e1s \u00fatiles para los responsables pol\u00edticos y los financiadores.  <\/p>\n\n<p><\/p>\n\n<h3 class=\"wp-block-heading\">Una frontera metodol\u00f3gica<\/h3>\n\n<p><\/p>\n\n<p>Una segunda capa de complejidad proviene de la naturaleza intersectorial de la prevenci\u00f3n de Una Salud. Los conjuntos de indicadores convencionales rara vez captan los beneficios colaterales que genera la prevenci\u00f3n -como la protecci\u00f3n de la biodiversidad, la seguridad del sistema alimentario o la resiliencia social- ni integran f\u00e1cilmente los datos de los sectores de la salud humana, animal y medioambiental. Traducir el riesgo emergente en carga econ\u00f3mica sigue siendo una frontera metodol\u00f3gica clave.  <\/p>\n\n<p>Por \u00faltimo, cualquier marco de indicadores debe ser a la vez riguroso y pr\u00e1ctico: representativo en entornos de bajos y altos recursos, comparable en todas las escalas y adaptable a los contextos locales y a las limitaciones de capacidad. Incluso cuando existen buenos indicadores, las barreras t\u00e9cnicas, institucionales y pol\u00edticas pueden impedir que impulsen la acci\u00f3n, y cerrar esa brecha ser\u00e1 uno de los puntos centrales del debate. <\/p>\n\n<h2 class=\"wp-block-heading\">Conoce a nuestros ponentes<\/h2>\n\n<div data-wp-context=\"{ &quot;autoclose&quot;: false, &quot;accordionItems&quot;: [] }\" data-wp-interactive=\"core\/accordion\" role=\"group\" class=\"wp-block-accordion is-layout-flow wp-block-accordion-is-layout-flow\">\n<div data-wp-class--is-open=\"state.isOpen\" data-wp-context=\"{ &quot;id&quot;: &quot;accordion-item-4&quot;, &quot;openByDefault&quot;: false }\" data-wp-init=\"callbacks.initAccordionItems\" data-wp-on-window--hashchange=\"callbacks.hashChange\" class=\"wp-block-accordion-item is-layout-flow wp-block-accordion-item-is-layout-flow\">\n<h3 class=\"wp-block-accordion-heading\"><button aria-expanded=\"false\" aria-controls=\"accordion-item-4-panel\" data-wp-bind--aria-expanded=\"state.isOpen\" data-wp-on--click=\"actions.toggle\" data-wp-on--keydown=\"actions.handleKeyDown\" id=\"accordion-item-4\" type=\"button\" class=\"wp-block-accordion-heading__toggle\"><span class=\"wp-block-accordion-heading__toggle-title\"><strong><strong>Profesora Wanda Markotter<\/strong><\/strong><\/span><span class=\"wp-block-accordion-heading__toggle-icon\" aria-hidden=\"true\">+<\/span><\/button><\/h3>\n\n\n\n<div inert aria-labelledby=\"accordion-item-4\" data-wp-bind--inert=\"!state.isOpen\" id=\"accordion-item-4-panel\" role=\"region\" class=\"wp-block-accordion-panel is-layout-flow wp-block-accordion-panel-is-layout-flow\">\n<p><strong>La profesora Wanda Markotter <\/strong>es Directora Interina y Catedr\u00e1tica de Investigaci\u00f3n: Personas, Salud y Lugares (One Health) en Future Africa, Universidad de Pretoria, Sud\u00e1frica. Tambi\u00e9n es Directora del Centro de Zoonosis V\u00edricas (UP-CVZ) de la Facultad de Ciencias de la Salud y titular de la C\u00e1tedra de Investigaci\u00f3n Sudafricana DSTI-NRF sobre Enfermedades Infecciosas de los Animales (Zoonosis). Su investigaci\u00f3n interdisciplinar se centra en los pat\u00f3genos de los murci\u00e9lagos y en la predicci\u00f3n y prevenci\u00f3n de los riesgos de propagaci\u00f3n en \u00c1frica. La Prof. Markotter es Copresidenta del Grupo de Expertos de Alto Nivel sobre Una Sola Salud (OHHLEP), que asesora a la OMS, la WOAH, la FAO y el PNUMA, y forma parte de la Comisi\u00f3n de The Lancet sobre Prevenci\u00f3n del Derrame. Sus resultados incluyen m\u00e1s de 100 publicaciones, ponencias en destacadas conferencias internacionales, varias contribuciones y art\u00edculos en la prensa popular y educativa, y apariciones en radio y televisi\u00f3n. Contribuye significativamente al desarrollo de capacidades; m\u00e1s de 75 estudiantes de posgrado se han graduado bajo su supervisi\u00f3n.sor Wanda Markotter     <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div data-wp-context=\"{ &quot;autoclose&quot;: false, &quot;accordionItems&quot;: [] }\" data-wp-interactive=\"core\/accordion\" role=\"group\" class=\"wp-block-accordion is-layout-flow wp-block-accordion-is-layout-flow\">\n<div data-wp-class--is-open=\"state.isOpen\" data-wp-context=\"{ &quot;id&quot;: &quot;accordion-item-5&quot;, &quot;openByDefault&quot;: false }\" data-wp-init=\"callbacks.initAccordionItems\" data-wp-on-window--hashchange=\"callbacks.hashChange\" class=\"wp-block-accordion-item is-layout-flow wp-block-accordion-item-is-layout-flow\">\n<h3 class=\"wp-block-accordion-heading\"><button aria-expanded=\"false\" aria-controls=\"accordion-item-5-panel\" data-wp-bind--aria-expanded=\"state.isOpen\" data-wp-on--click=\"actions.toggle\" data-wp-on--keydown=\"actions.handleKeyDown\" id=\"accordion-item-5\" type=\"button\" class=\"wp-block-accordion-heading__toggle\"><span class=\"wp-block-accordion-heading__toggle-title\"><strong>Dr. Osman Ahmed Dar<\/strong><\/span><span class=\"wp-block-accordion-heading__toggle-icon\" aria-hidden=\"true\">+<\/span><\/button><\/h3>\n\n\n\n<div inert aria-labelledby=\"accordion-item-5\" data-wp-bind--inert=\"!state.isOpen\" id=\"accordion-item-5-panel\" role=\"region\" class=\"wp-block-accordion-panel is-layout-flow wp-block-accordion-panel-is-layout-flow\">\n<p><strong>El Dr. Osman Ahmed<\/strong> Dar es miembro del Real Colegio de M\u00e9dicos (Edimburgo) y miembro de la Facultad de Salud P\u00fablica (Reino Unido), especializado en medicina de salud p\u00fablica y control de enfermedades transmisibles. Tiene una amplia experiencia internacional en el fortalecimiento de los sistemas sanitarios, la respuesta humanitaria y la seguridad sanitaria mundial, habiendo vivido y trabajado en Europa, \u00c1frica, Oriente Medio y Asia Meridional. <\/p>\n\n\n\n<p>En el \u00e1mbito internacional, Osman es Asesor Principal sobre Pol\u00edtica y Estrategia en la Oficina del Director General de los Centros Africanos para el Control y la Prevenci\u00f3n de Enfermedades, donde trabaja actualmente. Adem\u00e1s, es miembro del Grupo de Expertos de Alto Nivel de Una Sola Salud (OHHLEP), que asesora a la OMS, la WOAH, la FAO y el PNUMA sobre el desarrollo de sus estrategias mundiales de Una Sola Salud, incluidas sus actividades conjuntas sobre prevenci\u00f3n, preparaci\u00f3n y respuesta ante pandemias, control de zoonosis emergentes y otras crisis sanitarias en la interfaz hombre-animal-medio ambiente. En la actualidad, Osman tambi\u00e9n forma parte de la Comisi\u00f3n de Asesoramiento T\u00e9cnico del Fondo del Banco Mundial para Pandemias, un grupo de expertos independientes en la materia que eval\u00faan t\u00e9cnicamente todas las solicitudes de subvenci\u00f3n presentadas al Fondo.  <\/p>\n\n\n\n<p>En su puesto en la Agencia de Seguridad Sanitaria del Reino Unido (UKHSA), Osman es consultor m\u00e9dico superior en salud mundial, con una amplia cartera de actividades como responsable t\u00e9cnico operativo, supervisor educativo y acad\u00e9mico superior de investigaci\u00f3n que publica extensamente sobre salud p\u00fablica y disciplinas afines. Fue el principal autor coordinador de la Serie Lancet 2023 sobre Seguridad Sanitaria Mundial y Una Salud y autor colaborador de la Comisi\u00f3n Lancet Una Salud (2025). En Chatham House, Osman es Miembro Asociado del Programa de Salud Mundial. Su labor se centra principalmente en apoyar los proyectos de \u00abUna sola salud\u00bb del instituto, incluida la colaboraci\u00f3n multisectorial para la prevenci\u00f3n y el control de las enfermedades zoon\u00f3ticas, las infecciones emergentes, la seguridad alimentaria y la resistencia a los antimicrobianos.   <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div data-wp-context=\"{ &quot;autoclose&quot;: false, &quot;accordionItems&quot;: [] }\" data-wp-interactive=\"core\/accordion\" role=\"group\" class=\"wp-block-accordion is-layout-flow wp-block-accordion-is-layout-flow\">\n<div data-wp-class--is-open=\"state.isOpen\" data-wp-context=\"{ &quot;id&quot;: &quot;accordion-item-6&quot;, &quot;openByDefault&quot;: false }\" data-wp-init=\"callbacks.initAccordionItems\" data-wp-on-window--hashchange=\"callbacks.hashChange\" class=\"wp-block-accordion-item is-layout-flow wp-block-accordion-item-is-layout-flow\">\n<h3 class=\"wp-block-accordion-heading\"><button aria-expanded=\"false\" aria-controls=\"accordion-item-6-panel\" data-wp-bind--aria-expanded=\"state.isOpen\" data-wp-on--click=\"actions.toggle\" data-wp-on--keydown=\"actions.handleKeyDown\" id=\"accordion-item-6\" type=\"button\" class=\"wp-block-accordion-heading__toggle\"><span class=\"wp-block-accordion-heading__toggle-title\"><strong>Dr. Marc Leandri<\/strong><\/span><span class=\"wp-block-accordion-heading__toggle-icon\" aria-hidden=\"true\">+<\/span><\/button><\/h3>\n\n\n\n<div inert aria-labelledby=\"accordion-item-6\" data-wp-bind--inert=\"!state.isOpen\" id=\"accordion-item-6-panel\" role=\"region\" class=\"wp-block-accordion-panel is-layout-flow wp-block-accordion-panel-is-layout-flow\">\n<p><strong>El Dr. Marc Leandri<\/strong> es Profesor Asociado de Econom\u00eda en la UVSQ-Universidad de Par\u00eds Saclay e investigador en la UMI SOURCE-IRD. Su trabajo se centra en la econom\u00eda de la salud y el medio ambiente, con especial inter\u00e9s en los enfoques de \u00abUna sola salud\u00bb y la percepci\u00f3n del riesgo de las enfermedades transmitidas por vectores. Preside el Consejo de Expertos Socioecon\u00f3micos de la Agencia Francesa de Seguridad y Salud Alimentaria, Medioambiental y Laboral (ANSES). Tambi\u00e9n es investigador visitante en la Agencia Francesa de Desarrollo (AFD). Su investigaci\u00f3n actual aborda el valor econ\u00f3mico de las pol\u00edticas de prevenci\u00f3n de enfermedades zoon\u00f3ticas de Una Sola Salud en el Norte y el Sur Global.    <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div data-wp-context=\"{ &quot;autoclose&quot;: false, &quot;accordionItems&quot;: [] }\" data-wp-interactive=\"core\/accordion\" role=\"group\" class=\"wp-block-accordion is-layout-flow wp-block-accordion-is-layout-flow\">\n<div data-wp-class--is-open=\"state.isOpen\" data-wp-context=\"{ &quot;id&quot;: &quot;accordion-item-7&quot;, &quot;openByDefault&quot;: false }\" data-wp-init=\"callbacks.initAccordionItems\" data-wp-on-window--hashchange=\"callbacks.hashChange\" class=\"wp-block-accordion-item is-layout-flow wp-block-accordion-item-is-layout-flow\">\n<h3 class=\"wp-block-accordion-heading\"><button aria-expanded=\"false\" aria-controls=\"accordion-item-7-panel\" data-wp-bind--aria-expanded=\"state.isOpen\" data-wp-on--click=\"actions.toggle\" data-wp-on--keydown=\"actions.handleKeyDown\" id=\"accordion-item-7\" type=\"button\" class=\"wp-block-accordion-heading__toggle\"><span class=\"wp-block-accordion-heading__toggle-title\"><strong>Dra. Christina Pettan-Brewer<\/strong><\/span><span class=\"wp-block-accordion-heading__toggle-icon\" aria-hidden=\"true\">+<\/span><\/button><\/h3>\n\n\n\n<div inert aria-labelledby=\"accordion-item-7\" data-wp-bind--inert=\"!state.isOpen\" id=\"accordion-item-7-panel\" role=\"region\" class=\"wp-block-accordion-panel is-layout-flow wp-block-accordion-panel-is-layout-flow\">\n<p><strong>La Dra. Christina Pettan-Brewer<\/strong> es veterinaria, profesora asociada, educadora y l\u00edder mundial de Una Salud en la Facultad de Medicina de la Universidad de Washington. Su carrera abarca la investigaci\u00f3n acad\u00e9mica, la diplomacia internacional y el compromiso con la comunidad. Posee t\u00edtulos avanzados en medicina veterinaria y enfermedades infecciosas (DVM, MSc, tres becas postdoctorales, incluida la EID en los CDC) y un doctorado en Una Salud Global centrado en la Salud Ind\u00edgena. Con publicaciones revisadas por expertos, cap\u00edtulos de libros, informes y participaci\u00f3n en m\u00faltiples consejos editoriales, grupos de trabajo t\u00e9cnicos y comit\u00e9s directivos, aporta una amplia experiencia a la prevenci\u00f3n mundial de pandemias. Como asesora cient\u00edfica principal para las Am\u00e9ricas, ha dirigido iniciativas e implementaciones de Una Salud\/Ecosalud\/Salud Planetaria en todo el Sur Global desde 2010 y asesora a organizaciones internacionales. Tambi\u00e9n es redactora jefe de la publicaci\u00f3n de CABI \u00abM\u00e1s all\u00e1 de la salud de un oc\u00e9ano\u00bb. Nacida en Brasil, es vicepresidenta de ABRASUNI, fund\u00f3 y cofund\u00f3 las redes latinoamericanas de Una Salud y las iniciativas de OH, y ha dedicado m\u00e1s de 35 a\u00f1os a promover la salud humana y animal, la equidad, la inclusi\u00f3n y la sostenibilidad medioambiental en todo el mundo. (Las Am\u00e9ricas)       <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div data-wp-context=\"{ &quot;autoclose&quot;: false, &quot;accordionItems&quot;: [] }\" data-wp-interactive=\"core\/accordion\" role=\"group\" class=\"wp-block-accordion is-layout-flow wp-block-accordion-is-layout-flow\">\n<div data-wp-class--is-open=\"state.isOpen\" data-wp-context=\"{ &quot;id&quot;: &quot;accordion-item-8&quot;, &quot;openByDefault&quot;: false }\" data-wp-init=\"callbacks.initAccordionItems\" data-wp-on-window--hashchange=\"callbacks.hashChange\" class=\"wp-block-accordion-item is-layout-flow wp-block-accordion-item-is-layout-flow\">\n<h3 class=\"wp-block-accordion-heading\"><button aria-expanded=\"false\" aria-controls=\"accordion-item-8-panel\" data-wp-bind--aria-expanded=\"state.isOpen\" data-wp-on--click=\"actions.toggle\" data-wp-on--keydown=\"actions.handleKeyDown\" id=\"accordion-item-8\" type=\"button\" class=\"wp-block-accordion-heading__toggle\"><span class=\"wp-block-accordion-heading__toggle-title\"><strong>Yoeri Booijink<\/strong><\/span><span class=\"wp-block-accordion-heading__toggle-icon\" aria-hidden=\"true\">+<\/span><\/button><\/h3>\n\n\n\n<div inert aria-labelledby=\"accordion-item-8\" data-wp-bind--inert=\"!state.isOpen\" id=\"accordion-item-8-panel\" role=\"region\" class=\"wp-block-accordion-panel is-layout-flow wp-block-accordion-panel-is-layout-flow\">\n<p><strong>Yoeri Booijink <\/strong>es Economista de Una Sola Salud en el CIRAD, especializado en la evaluaci\u00f3n del Retorno de la Inversi\u00f3n (ROI) del Enfoque de Una Sola Salud. Es Colaborador del Grupo B\u00e1sico de la Comunidad de Pr\u00e1ctica (CoP) impulsada por el Cuatripartito sobre el Retorno de la Inversi\u00f3n en Una Salud y la Planificaci\u00f3n de la Inversi\u00f3n en Una Salud. Esta iniciativa inclusiva y multipartita se centra en el desarrollo de v\u00edas de inversi\u00f3n y en proporcionar orientaci\u00f3n para ayudar a los pa\u00edses en sus evaluaciones econ\u00f3micas y en la planificaci\u00f3n nacional de la inversi\u00f3n en Una Sola Salud. Licenciado en Ciencia y Econom\u00eda Animal por la Universidad de Wageningen, Yoeri tiende puentes entre la teor\u00eda econ\u00f3mica y la realidad agr\u00edcola; adem\u00e1s de investigar, es un activo ganadero lechero en los Pa\u00edses Bajos, que aporta una perspectiva pr\u00e1ctica a las estrategias de inversi\u00f3n en salud mundial.   <\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El 5 de marzo de 2026, PREZODE convocar\u00e1 una mesa redonda para examinar c\u00f3mo definir y medir indicadores que capten el valor a\u00f1adido y el impacto de la prevenci\u00f3n de las enfermedades zoon\u00f3ticas. Prevenir la aparici\u00f3n de enfermedades zoon\u00f3ticas es uno de los retos definitorios de nuestro tiempo, y uno que es intr\u00ednsecamente intersectorial. En<a href=\"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/\">Continue reading <span class=\"sr-only\">\u00ab\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":4447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[170],"tags":[],"news_type":[152,155],"class_list":["post-4443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seminarios-web","news_type-articulo","news_type-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de &quot;Una sola salud&quot;? - %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de &quot;Una sola salud&quot;? - %\" \/>\n<meta property=\"og:description\" content=\"El 5 de marzo de 2026, PREZODE convocar\u00e1 una mesa redonda para examinar c\u00f3mo definir y medir indicadores que capten el valor a\u00f1adido y el impacto de la prevenci\u00f3n de las enfermedades zoon\u00f3ticas. Prevenir la aparici\u00f3n de enfermedades zoon\u00f3ticas es uno de los retos definitorios de nuestro tiempo, y uno que es intr\u00ednsecamente intersectorial. EnContinue reading &quot;\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Prezode\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-24T14:02:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T16:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"prezode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"prezode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/\"},\"author\":{\"name\":\"prezode\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#\\\/schema\\\/person\\\/2b1e3ca432542580f3096e4b35bd5e24\"},\"headline\":\"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?\",\"datePublished\":\"2026-02-24T14:02:45+00:00\",\"dateModified\":\"2026-03-25T16:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/\"},\"wordCount\":1693,\"publisher\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image-Web-Indic.png\",\"articleSection\":[\"Seminarios web\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/\",\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/\",\"name\":\"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \\\"Una sola salud\\\"? - %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image-Web-Indic.png\",\"datePublished\":\"2026-02-24T14:02:45+00:00\",\"dateModified\":\"2026-03-25T16:48:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image-Web-Indic.png\",\"contentUrl\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image-Web-Indic.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00ab\u00a0Una sola salud\u00a0\u00bb?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/\",\"name\":\"Prezode\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#organization\",\"name\":\"Prezode\",\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"width\":168,\"height\":118,\"caption\":\"Prezode\"},\"image\":{\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/#\\\/schema\\\/person\\\/2b1e3ca432542580f3096e4b35bd5e24\",\"name\":\"prezode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g\",\"caption\":\"prezode\"},\"url\":\"https:\\\/\\\/prezode-initiative.org\\\/es\\\/author\\\/prezode\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \"Una sola salud\"? - %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \"Una sola salud\"? - %","og_description":"El 5 de marzo de 2026, PREZODE convocar\u00e1 una mesa redonda para examinar c\u00f3mo definir y medir indicadores que capten el valor a\u00f1adido y el impacto de la prevenci\u00f3n de las enfermedades zoon\u00f3ticas. Prevenir la aparici\u00f3n de enfermedades zoon\u00f3ticas es uno de los retos definitorios de nuestro tiempo, y uno que es intr\u00ednsecamente intersectorial. EnContinue reading \"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?\"","og_url":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/","og_site_name":"Prezode","article_published_time":"2026-02-24T14:02:45+00:00","article_modified_time":"2026-03-25T16:48:22+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png","type":"image\/png"}],"author":"prezode","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"prezode","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#article","isPartOf":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/"},"author":{"name":"prezode","@id":"https:\/\/prezode-initiative.org\/es\/#\/schema\/person\/2b1e3ca432542580f3096e4b35bd5e24"},"headline":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00abUna sola salud\u00bb?","datePublished":"2026-02-24T14:02:45+00:00","dateModified":"2026-03-25T16:48:22+00:00","mainEntityOfPage":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/"},"wordCount":1693,"publisher":{"@id":"https:\/\/prezode-initiative.org\/es\/#organization"},"image":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png","articleSection":["Seminarios web"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/","url":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/","name":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \"Una sola salud\"? - %","isPartOf":{"@id":"https:\/\/prezode-initiative.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#primaryimage"},"image":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png","datePublished":"2026-02-24T14:02:45+00:00","dateModified":"2026-03-25T16:48:22+00:00","breadcrumb":{"@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#primaryimage","url":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png","contentUrl":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2026\/02\/image-Web-Indic.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/prezode-initiative.org\/es\/como-podemos-evaluar-el-valor-anadido-y-el-impacto-de-las-estrategias-de-prevencion-de-una-sola-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prezode-initiative.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo podemos evaluar el valor a\u00f1adido y el impacto de las estrategias de prevenci\u00f3n de \u00ab\u00a0Una sola salud\u00a0\u00bb?"}]},{"@type":"WebSite","@id":"https:\/\/prezode-initiative.org\/es\/#website","url":"https:\/\/prezode-initiative.org\/es\/","name":"Prezode","description":"","publisher":{"@id":"https:\/\/prezode-initiative.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prezode-initiative.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/prezode-initiative.org\/es\/#organization","name":"Prezode","url":"https:\/\/prezode-initiative.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prezode-initiative.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","contentUrl":"https:\/\/prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","width":168,"height":118,"caption":"Prezode"},"image":{"@id":"https:\/\/prezode-initiative.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prezode-initiative.org\/es\/#\/schema\/person\/2b1e3ca432542580f3096e4b35bd5e24","name":"prezode","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56cf4262506f21c40bdb802791c01348323e4e66e5b18058bc077865ebe7489a?s=96&d=mm&r=g","caption":"prezode"},"url":"https:\/\/prezode-initiative.org\/es\/author\/prezode\/"}]}},"_links":{"self":[{"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/posts\/4443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/comments?post=4443"}],"version-history":[{"count":2,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/posts\/4443\/revisions"}],"predecessor-version":[{"id":4455,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/posts\/4443\/revisions\/4455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/media\/4447"}],"wp:attachment":[{"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/media?parent=4443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/categories?post=4443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/tags?post=4443"},{"taxonomy":"news_type","embeddable":true,"href":"https:\/\/prezode-initiative.org\/es\/wp-json\/wp\/v2\/news_type?post=4443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}